{"id":760,"date":"2021-07-08T18:20:11","date_gmt":"2021-07-08T23:20:11","guid":{"rendered":"https:\/\/viaexcelencia.com.mx\/?p=760"},"modified":"2021-07-08T18:33:10","modified_gmt":"2021-07-08T23:33:10","slug":"como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2","status":"publish","type":"post","link":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/","title":{"rendered":"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica?"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-1-1024x683.jpg\" alt=\"\" class=\"wp-image-761\" width=\"563\" height=\"375\" srcset=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-1-1024x683.jpg 1024w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-1-300x200.jpg 300w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-1-768x512.jpg 768w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-1-1536x1024.jpg 1536w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-1-2048x1365.jpg 2048w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-1-600x400.jpg 600w\" sizes=\"(max-width: 563px) 100vw, 563px\" \/><\/figure><\/div>\n\n\n\n<p>El papel del docente mantiene estrecha relaci\u00f3n con la promoci\u00f3n de la calidad educativa y con el logro de los aprendizajes de los estudiantes. En educaci\u00f3n b\u00e1sica, los retos a los que se enfrentan los docentes son diversos debido a la complejidad del proceso de ense\u00f1anza y aprendizaje y a los factores que influyen en el rendimiento acad\u00e9mico.<\/p>\n\n\n\n<p>Para ello, existen estrategias did\u00e1cticas que pueden potenciar de manera significativa el avance de los aprendizajes en el \u00e1rea de lenguaje y comunicaci\u00f3n, considerando que todo proceso educativo se fundamenta en la relaci\u00f3n interpersonal y en la consolidaci\u00f3n del proyecto personal dentro de un grupo social, lo cual no ser\u00eda posible sin el lenguaje, entendido como una herramienta poderosa para aprender, ense\u00f1ar, generar acciones y provocar cambios tanto a nivel personal como en el entorno (Urgil\u00e9s, 2016).<\/p>\n\n\n\n<p>Bajo este enfoque, se sostiene la idea de que el lenguaje se adquiere y educa en la interacci\u00f3n social, mediante la participaci\u00f3n en intercambios orales variados y en actos de lectura y escritura plenos de significado (Secretar\u00eda de Educaci\u00f3n P\u00fablica, 2017).<\/p>\n\n\n\n<p><span style=\"color:#960539\" class=\"has-inline-color\"><strong><em>\u00bfQu\u00e9 estrategias podemos implementar?<\/em><\/strong> <\/span><\/p>\n\n\n\n<p>A continuaci\u00f3n, se presentan algunas propuestas de acciones pedag\u00f3gicas de fortalecimiento educativo para el campo de lenguaje y comunicaci\u00f3n, las cuales son de car\u00e1cter enunciativo, y en ning\u00fan caso limitativo, siempre con la intenci\u00f3n de mejorar el desempe\u00f1o acad\u00e9mico de los estudiantes:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"773\" height=\"518\" src=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img2.jpg\" alt=\"\" class=\"wp-image-751\" srcset=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img2.jpg 773w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img2-300x201.jpg 300w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img2-768x515.jpg 768w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img2-600x402.jpg 600w\" sizes=\"(max-width: 773px) 100vw, 773px\" \/><\/figure>\n\n\n\n<ul><li><strong>Diagnosticar, idear y planificar.<\/strong> A partir de la identificaci\u00f3n de las dificultades cognitivas de los estudiantes, es importante <strong>enfrentarlos a tareas<\/strong> que los desaf\u00eden a usar la lectura para objetivos cada vez m\u00e1s complejos (Crespo, Garc\u00eda y Carvajal, 2003) y, que sean ellos mismos los que observen su desarrollo en cada desaf\u00edo.<\/li><li>Implementar estrategias para desarrollar en los estudiantes una <strong>mayor motivaci\u00f3n<\/strong> hacia la lectura, tales como:<ul><li>Propiciar que el estudiante interiorice la importancia del por qu\u00e9 lee y para qu\u00e9 le sirve la lectura.<\/li><\/ul><ul><li>Incorporar herramientas y aplicaciones digitales como fomento para leer m\u00e1s.<\/li><\/ul><ul><li>Seleccionar textos que est\u00e9n sintonizados o acordes con los intereses y necesidades de las edades de los estudiantes a quienes se ense\u00f1a (Sedano, 2015).<\/li><\/ul><\/li><li><strong>D<\/strong><strong>ise\u00f1ar propuestas de intervenci\u00f3n pedag\u00f3gica<\/strong> encaminadas a identificar la estructura de los textos, a formular cuestionamientos, a deducir diversos elementos dentro del mismo, a usar las pistas gramaticales, a elaborar inferencias, a recuperar datos, a efectuar conexiones entre la nueva informaci\u00f3n y los conocimientos previos, a identificar los objetivos de la lectura y a reaccionar, evaluar y reflexionar frente a los portadores de texto, entre otras <strong>habilidades de lectura<\/strong> (Hoyos y Gallego, 2017).<\/li><li>Para una id\u00f3nea competencia comunicativa, es necesario ayudar a los lectores a aprender la l\u00f3gica de los textos e identificar las estructuras que los componen, condiciones que se logran a trav\u00e9s de su <strong>acercamiento a los diversos portadores de texto<\/strong> (Hoyos y Gallego, 2017).<\/li><\/ul>\n\n\n\n<ul><li>Dise\u00f1ar estrategias pedag\u00f3gicas que <strong>integren lectura y oralidad<\/strong> en la producci\u00f3n de textos escritos y que involucren tambi\u00e9n diversas \u00e1reas curriculares (Barrag\u00e1n, 2013), favoreciendo de esta manera la interdisciplinariedad, lo que permitir\u00e1 al estudiante relacionar todo lo que aprende y los usos que puede darle.<\/li><li>Incluir en las pr\u00e1cticas escolares de lectura actividades relacionadas con <strong>lo que se hace con la lectura en el medio social,<\/strong> es decir, pr\u00e1cticas relacionadas con el contexto sociocultural en el que se desenvuelven los estudiantes (Barboza y Pe\u00f1a, 2014). Por ejemplo:<ul><li>Leer para informarse sobre alguna noticia que ha impactado a todos.<\/li><li>Leer el programa de las actividades culturales para elegir a cu\u00e1l asistir.<\/li><li>Conversar sobre el libro que le\u00edmos y el placer que nos produjo.<\/li><li>Leer una receta para prepararla.<\/li><li>Compartir las instrucciones del manual de procedimientos para poner a funcionar alg\u00fan equipo tecnol\u00f3gico de la escuela o de casa.<\/li><li>Leer un correo enviado por un compa\u00f1ero.<\/li><li>Leer un formulario para llenarlo.<\/li><li>Leer un texto en la Web sobre un tema de nuestro inter\u00e9s, entre otros (Pe\u00f1a, Serrano de Moreno y Aguirre de Ram\u00edrez, 2009).<\/li><\/ul><\/li><li>Fomentar en las escuelas las <strong>salas infantiles y juveniles<\/strong> <strong>con clubes <\/strong><strong>de lectura<\/strong>, as\u00ed como fomentar la participaci\u00f3n de las bibliotecas p\u00fablicas y digitales en los procesos de promoci\u00f3n de lectura, a fin de formar lectores \u00e1vidos y competentes (Hoyos y Gallego, 2017).<\/li><\/ul>\n\n\n\n<ul><li>Promover el <strong>dominio de las diferentes estructuras gramaticales<\/strong> y su empleo adecuado en las variadas situaciones comunicativas a que se enfrenta y en dependencia de sus interlocutores. Esta propuesta metodol\u00f3gica est\u00e1 orientada a hacer conscientes a los estudiantes de la funcionalidad de los contenidos gramaticales (Toledo, Godoy y Su\u00e1rez, 2008).<\/li><li>Proporcionar herramientas para la reflexi\u00f3n contextualizada de la lengua y sus caracter\u00edsticas, a partir de la identificaci\u00f3n de los elementos que condicionan el uso de los diferentes morfemas, dado que un buen empleo del espa\u00f1ol radica en el uso adecuado de sus significados. Por lo tanto, la incorporaci\u00f3n del an\u00e1lisis morfol\u00f3gico como mecanismo para <strong>enriquecer el vocabulario<\/strong> crea espacios para desarrollar el pensamiento anal\u00f3gico y anal\u00edtico mediante la reflexi\u00f3n metaling\u00fc\u00edstica (Murillo, 2011).<\/li><li>Fomentar las pr\u00e1cticas de <strong>lenguaje escrito para fines acad\u00e9micos y personales<\/strong>, es decir, la comprensi\u00f3n y producci\u00f3n de textos escritos que permitan la construcci\u00f3n y articulaci\u00f3n significativa de conocimientos de los diferentes campos formativos y \u00e1reas de la vida diaria. Estas pr\u00e1cticas permiten al alumnado desde su inicio escolar, vincular las pr\u00e1cticas de lectura de las que son portadores con los usos acad\u00e9micos y personales de la lengua escrita (Pe\u00f1a et al., 2009).<\/li><li>Por \u00faltimo, es importante implementar <strong>estrategias de evaluaci\u00f3n flexibles<\/strong> como sea posible para evitar en los estudiantes el efecto psicol\u00f3gico de un resultado impositivo (Sedano, 2015), motivando cada logro, acci\u00f3n y esfuerzo empleado, as\u00ed como proporcionar la retroalimentaci\u00f3n de los desempe\u00f1os de manera oportuna.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen3.jpg\" alt=\"\" class=\"wp-image-753\" width=\"578\" height=\"384\" srcset=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen3.jpg 863w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen3-300x200.jpg 300w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen3-768x511.jpg 768w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen3-600x399.jpg 600w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen2.jpg\" alt=\"\" class=\"wp-image-754\" width=\"575\" height=\"382\" srcset=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen2.jpg 899w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen2-300x200.jpg 300w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen2-768x512.jpg 768w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Imagen2-600x400.jpg 600w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><\/figure><\/div>\n\n\n\n<p><strong><em><span style=\"color:#960539\" class=\"has-inline-color\">Decisiones de mejora<\/span><\/em><\/strong><\/p>\n\n\n\n<p>Estas ideas invitan a los docentes a dise\u00f1ar, implementar y evaluar propuestas pedag\u00f3gicas que los ayuden a transformar las pr\u00e1cticas de la ense\u00f1anza de la lectura y la escritura en sus escuelas; para ello, el aprendizaje de la did\u00e1ctica de lectura y la escritura es clave para su desarrollo eficaz. En este sentido, la formaci\u00f3n y actualizaci\u00f3n de los docentes a trav\u00e9s de diferentes espacios formativos los llevar\u00e1 a poner en pr\u00e1ctica principios pedag\u00f3gicos que sustenten conceptualmente las estrategias did\u00e1cticas organizadas para leer y para escribir, as\u00ed como los modelos explicativos que permiten el dise\u00f1o efectivo de situaciones de aprendizaje.<\/p>\n\n\n\n<p><strong><em>Para reflexionar\u2026<\/em><\/strong><\/p>\n\n\n\n<ul><li>\u00bfSon pertinentes estas estrategias para tu nivel educativo?<\/li><li>\u00bfHas implementado alguna de ellas? Si es as\u00ed, \u00bfqu\u00e9 resultados obtuviste?<\/li><li>\u00bfQu\u00e9 adaptaciones le har\u00edas?<\/li><li>\u00bfHas tenido \u00e9xito con otras estrategias? \u00a1Cu\u00e9ntanos! Te leemos.<\/li><\/ul>\n\n\n\n<p>\u00bfTe gustar\u00eda aprender m\u00e1s de estos temas?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Iconos-VE-color-19.png\" alt=\"\" class=\"wp-image-755\" width=\"138\" height=\"137\" srcset=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Iconos-VE-color-19.png 591w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Iconos-VE-color-19-300x300.png 300w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Iconos-VE-color-19-150x150.png 150w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Iconos-VE-color-19-100x100.png 100w\" sizes=\"(max-width: 138px) 100vw, 138px\" \/><\/figure><\/div>\n\n\n\n<p><strong><em><span style=\"color:#960539\" class=\"has-inline-color\">Referencias<\/span><\/em><\/strong><\/p>\n\n\n\n<p>Barboza, F. y Pe\u00f1a, F. (enero-abril, 2014). El problema de la ense\u00f1anza de la lectura en educaci\u00f3n primaria. <em>Educere, 18<\/em>( 59), 133-142. Recuperado de https:\/\/www.redalyc.org\/pdf\/356\/35631103015.pdf<\/p>\n\n\n\n<p>Barrag\u00e1n, F. (enero-abril, 2013). Criterios para transformar la did\u00e1ctica de la producci\u00f3n de textos escritos en la educaci\u00f3n b\u00e1sica primaria. <em>Innovaci\u00f3n Educativa, 13<\/em>(61), 85-105. Recuperado de https:\/\/www.redalyc.org\/pdf\/1794\/179427877006.pdf<\/p>\n\n\n\n<p>Crespo, N.; Garc\u00eda, G. y Carvajal, C. (2003). Concepciones did\u00e1cticas de la lectura: su influencia en el saber de los escolares. <em>Onom\u00e1zein<\/em>, 8, 161-174. Recuperado de https:\/\/www.redalyc.org\/pdf\/1345\/134517976013.pdf<\/p>\n\n\n\n<p>Hoyos, A. y Gallego, M. (mayo-agosto, 2017). Desarrollo de habilidades de comprensi\u00f3n lectora en ni\u00f1os y ni\u00f1as de la b\u00e1sica primaria. <em>Revista Virtual Universidad Cat\u00f3lica del Norte<\/em>, 51, Recuperado de https:\/\/www.redalyc.org\/pdf\/1942\/194252398003.pdf<\/p>\n\n\n\n<p>Murillo, M. (2011). An\u00e1lisis morfol\u00f3gico y ense\u00f1anza del vocabulario en la educaci\u00f3n primaria. <em>Revista K\u00e1\u00f1ina, XXXV<\/em>(1), 139-152. Recuperado de https:\/\/www.redalyc.org\/pdf\/442\/44248789010.pdf<\/p>\n\n\n\n<p>Pe\u00f1a, F.; Serrano de Moreno, M. y Aguirre de Ram\u00edrez, R. (julio-septiembre, 2009). Pr\u00e1cticas de lectura en escolares de la primera etapa de Educaci\u00f3n B\u00e1sica. <em>Educere, 13<\/em>(46),&nbsp; 741-750. Recuperado de https:\/\/www.redalyc.org\/pdf\/356\/35613218019.pdf<\/p>\n\n\n\n<p>Secretar\u00eda de Educaci\u00f3n P\u00fablica (2017). <em>Aprendizajes clave para la educaci\u00f3n integral. Lengua Materna. Espa\u00f1ol. Educaci\u00f3n secundaria Plan y programas de estudio, orientaciones did\u00e1cticas y sugerencias de evaluaci\u00f3n<\/em>. Recuperado de https:\/\/www.planyprogramasdestudio.sep.gob.mx\/descargables\/biblioteca\/secundaria\/espanol\/1-LpM-Secundaria-Espanol.pdf<\/p>\n\n\n\n<p>Sedano, M. (2015). Leer en el aula: propuesta para mejorar la lectura en secundaria. <em>Opci\u00f3n, 31<\/em>(6), 1136-1159. Recuperado de https:\/\/www.redalyc.org\/pdf\/310\/31045571062.pdf<\/p>\n\n\n\n<p>Toledo, A.; Godoy, M. y Su\u00e1rez, Z. (2008). El an\u00e1lisis sem\u00e1ntico, sint\u00e1ctico y pragm\u00e1tico en la ense\u00f1anza de los contenidos gramaticales. <em>VARONA<\/em>, 46, 60-65. Recuperado de https:\/\/www.redalyc.org\/pdf\/3606\/360635566010.pdf<\/p>\n\n\n\n<p>Urgil\u00e9s, G. (2016). Aula, lenguaje y educaci\u00f3n. <em>Sophia, Colecci\u00f3n de Filosof\u00eda de la Educaci\u00f3n<\/em>, 20, 221-244. Recuperado de https:\/\/dialnet.unirioja.es\/descarga\/articulo\/5973076.pdf<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El papel del docente mantiene estrecha relaci\u00f3n con la promoci\u00f3n de la calidad educativa y con el logro de los aprendizajes de los estudiantes. En educaci\u00f3n b\u00e1sica, los retos a los que se enfrentan los docentes son diversos debido a la complejidad del proceso de ense\u00f1anza y aprendizaje y a los factores que influyen en el rendimiento acad\u00e9mico&#8230;.<\/p>\n","protected":false},"author":2,"featured_media":761,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica? - Instituto V\u00eda Excelencia<\/title>\n<meta name=\"description\" content=\"El papel del docente mantiene estrecha relaci\u00f3n con la promoci\u00f3n de la calidad educativa y con el logro de los aprendizajes de los estudiantes. En educaci\u00f3n b\u00e1sica, los retos a los que se enfrentan los docentes son diversos debido a la complejidad del proceso de ense\u00f1anza y aprendizaje y a los factores que influyen en el rendimiento acad\u00e9mico....\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica? - Instituto V\u00eda Excelencia\" \/>\n<meta property=\"og:description\" content=\"El papel del docente mantiene estrecha relaci\u00f3n con la promoci\u00f3n de la calidad educativa y con el logro de los aprendizajes de los estudiantes. En educaci\u00f3n b\u00e1sica, los retos a los que se enfrentan los docentes son diversos debido a la complejidad del proceso de ense\u00f1anza y aprendizaje y a los factores que influyen en el rendimiento acad\u00e9mico....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto V\u00eda Excelencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutoviaexcelencia\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-08T23:20:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-08T23:33:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dra. Erika Vera Cetina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dra. Erika Vera Cetina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/\"},\"author\":{\"name\":\"Dra. Erika Vera Cetina\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/#\/schema\/person\/619fe30342434fd22b2e24aff6fd2a34\"},\"headline\":\"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica?\",\"datePublished\":\"2021-07-08T23:20:11+00:00\",\"dateModified\":\"2021-07-08T23:33:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/\"},\"wordCount\":1520,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/#organization\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/\",\"url\":\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/\",\"name\":\"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica? - Instituto V\u00eda Excelencia\",\"isPartOf\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/#website\"},\"datePublished\":\"2021-07-08T23:20:11+00:00\",\"dateModified\":\"2021-07-08T23:33:10+00:00\",\"description\":\"El papel del docente mantiene estrecha relaci\u00f3n con la promoci\u00f3n de la calidad educativa y con el logro de los aprendizajes de los estudiantes. En educaci\u00f3n b\u00e1sica, los retos a los que se enfrentan los docentes son diversos debido a la complejidad del proceso de ense\u00f1anza y aprendizaje y a los factores que influyen en el rendimiento acad\u00e9mico....\",\"breadcrumb\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/viaexcelencia.com.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/#website\",\"url\":\"https:\/\/viaexcelencia.com.mx\/\",\"name\":\"Instituto V\u00eda Excelencia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/viaexcelencia.com.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/#organization\",\"name\":\"Instituto V\u00eda Excelencia\",\"url\":\"https:\/\/viaexcelencia.com.mx\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/institutoviaexcelencia\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Logotipo-VE-final-07.png\",\"contentUrl\":\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Logotipo-VE-final-07.png\",\"width\":2629,\"height\":1021,\"caption\":\"Instituto V\u00eda Excelencia\"},\"image\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/#\/schema\/person\/619fe30342434fd22b2e24aff6fd2a34\",\"name\":\"Dra. Erika Vera Cetina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e54287d0ecabfd11a4f104bd586e5c51?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e54287d0ecabfd11a4f104bd586e5c51?s=96&d=mm&r=g\",\"caption\":\"Dra. Erika Vera Cetina\"},\"description\":\"Fundadora y Directora general del Instituto V\u00eda Excelencia erika.vera@viaexcelencia.com.mx\",\"sameAs\":[\"https:\/\/viaexcelencia.com.mx\"],\"url\":\"https:\/\/viaexcelencia.com.mx\/index.php\/author\/erika\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica? - Instituto V\u00eda Excelencia","description":"El papel del docente mantiene estrecha relaci\u00f3n con la promoci\u00f3n de la calidad educativa y con el logro de los aprendizajes de los estudiantes. En educaci\u00f3n b\u00e1sica, los retos a los que se enfrentan los docentes son diversos debido a la complejidad del proceso de ense\u00f1anza y aprendizaje y a los factores que influyen en el rendimiento acad\u00e9mico....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica? - Instituto V\u00eda Excelencia","og_description":"El papel del docente mantiene estrecha relaci\u00f3n con la promoci\u00f3n de la calidad educativa y con el logro de los aprendizajes de los estudiantes. En educaci\u00f3n b\u00e1sica, los retos a los que se enfrentan los docentes son diversos debido a la complejidad del proceso de ense\u00f1anza y aprendizaje y a los factores que influyen en el rendimiento acad\u00e9mico....","og_url":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/","og_site_name":"Instituto V\u00eda Excelencia","article_publisher":"https:\/\/www.facebook.com\/institutoviaexcelencia","article_published_time":"2021-07-08T23:20:11+00:00","article_modified_time":"2021-07-08T23:33:10+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-scaled.jpg","type":"image\/jpeg"}],"author":"Dra. Erika Vera Cetina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dra. Erika Vera Cetina","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/#article","isPartOf":{"@id":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/"},"author":{"name":"Dra. Erika Vera Cetina","@id":"https:\/\/viaexcelencia.com.mx\/#\/schema\/person\/619fe30342434fd22b2e24aff6fd2a34"},"headline":"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica?","datePublished":"2021-07-08T23:20:11+00:00","dateModified":"2021-07-08T23:33:10+00:00","mainEntityOfPage":{"@id":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/"},"wordCount":1520,"commentCount":0,"publisher":{"@id":"https:\/\/viaexcelencia.com.mx\/#organization"},"articleSection":["Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/","url":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/","name":"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica? - Instituto V\u00eda Excelencia","isPartOf":{"@id":"https:\/\/viaexcelencia.com.mx\/#website"},"datePublished":"2021-07-08T23:20:11+00:00","dateModified":"2021-07-08T23:33:10+00:00","description":"El papel del docente mantiene estrecha relaci\u00f3n con la promoci\u00f3n de la calidad educativa y con el logro de los aprendizajes de los estudiantes. En educaci\u00f3n b\u00e1sica, los retos a los que se enfrentan los docentes son diversos debido a la complejidad del proceso de ense\u00f1anza y aprendizaje y a los factores que influyen en el rendimiento acad\u00e9mico....","breadcrumb":{"@id":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/viaexcelencia.com.mx\/index.php\/2021\/07\/08\/como-fortalecer-el-desarrollo-de-competencias-de-lenguaje-y-comunicacion-en-estudiantes-de-educacion-basica-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/viaexcelencia.com.mx\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo fortalecer el desarrollo de competencias de lenguaje y comunicaci\u00f3n en estudiantes de educaci\u00f3n b\u00e1sica?"}]},{"@type":"WebSite","@id":"https:\/\/viaexcelencia.com.mx\/#website","url":"https:\/\/viaexcelencia.com.mx\/","name":"Instituto V\u00eda Excelencia","description":"","publisher":{"@id":"https:\/\/viaexcelencia.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viaexcelencia.com.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/viaexcelencia.com.mx\/#organization","name":"Instituto V\u00eda Excelencia","url":"https:\/\/viaexcelencia.com.mx\/","sameAs":["https:\/\/www.facebook.com\/institutoviaexcelencia"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/viaexcelencia.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Logotipo-VE-final-07.png","contentUrl":"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Logotipo-VE-final-07.png","width":2629,"height":1021,"caption":"Instituto V\u00eda Excelencia"},"image":{"@id":"https:\/\/viaexcelencia.com.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/viaexcelencia.com.mx\/#\/schema\/person\/619fe30342434fd22b2e24aff6fd2a34","name":"Dra. Erika Vera Cetina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/viaexcelencia.com.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e54287d0ecabfd11a4f104bd586e5c51?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e54287d0ecabfd11a4f104bd586e5c51?s=96&d=mm&r=g","caption":"Dra. Erika Vera Cetina"},"description":"Fundadora y Directora general del Instituto V\u00eda Excelencia erika.vera@viaexcelencia.com.mx","sameAs":["https:\/\/viaexcelencia.com.mx"],"url":"https:\/\/viaexcelencia.com.mx\/index.php\/author\/erika\/"}]}},"jetpack_featured_media_url":"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/img1-1-scaled.jpg","_links":{"self":[{"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/760"}],"collection":[{"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=760"}],"version-history":[{"count":3,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/760\/revisions"}],"predecessor-version":[{"id":766,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/760\/revisions\/766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/media\/761"}],"wp:attachment":[{"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}