{"id":81,"date":"2021-03-31T05:36:52","date_gmt":"2021-03-31T05:36:52","guid":{"rendered":"https:\/\/viaexcelencia.com.mx\/?page_id=81"},"modified":"2021-07-26T09:28:00","modified_gmt":"2021-07-26T14:28:00","slug":"vinculacion-comunitaria","status":"publish","type":"page","link":"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/","title":{"rendered":"Vinculaci\u00f3n comunitaria"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"81\" class=\"elementor elementor-81\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c675621 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7c675621\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2609d6fb\" data-id=\"2609d6fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56e5165a elementor-widget elementor-widget-heading\" data-id=\"56e5165a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">VinculACI\u00d3N cOMUNITARIA<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65fbfafd\" data-id=\"65fbfafd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-542466dd elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"542466dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e40d039\" data-id=\"1e40d039\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69ba5bcd elementor-widget elementor-widget-heading\" data-id=\"69ba5bcd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">Principio de crecimiento de comunidades de aprendizaje<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-74584f2d\" data-id=\"74584f2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd817ff elementor-widget elementor-widget-text-editor\" data-id=\"fd817ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En el Instituto V\u00eda Excelencia nos basamos en el principio del crecimiento de comunidades de aprendizaje para el desarrollo de comunidades sociales, es por ello que participamos en la importante tarea de generar espacios donde nuestros estudiantes, clientes, voluntarios y donantes sean parte de acciones que vinculen sus aprendizajes a las necesidades sociales de su entorno a trav\u00e9s de propuestas, proyectos o acciones encaminadas a apoyar y promover el cambio y la transformaci\u00f3n social de comunidades.<\/p><p>\u00a0<\/p><p>El Instituto V\u00eda Excelencia concibe tres formas de vinculaci\u00f3n comunitaria a trav\u00e9s de: Acciones en comunidad, iniciativas y proyectos externos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61f12f9b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61f12f9b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64da0b0a\" data-id=\"64da0b0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71b4143a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"71b4143a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14c91ab6 elementor-widget elementor-widget-heading\" data-id=\"14c91ab6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Acciones en comunidad<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7d7de9e6\" data-id=\"7d7de9e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c9e5dcc elementor-widget elementor-widget-text-editor\" data-id=\"5c9e5dcc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Son las intervenciones situadas en contextos particulares que realiza el Instituto V\u00eda Excelencia para promover el bienestar, la capacitaci\u00f3n para el trabajo, el desarrollo sostenible y el aprendizaje continuo.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc675c3 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"cc675c3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"2629\" height=\"1022\" src=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Logotipo-VE-final-11.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/figure><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62e9015 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62e9015\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-743b9bca\" data-id=\"743b9bca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12105f4f elementor-widget elementor-widget-heading\" data-id=\"12105f4f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00danete como voluntario<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9d88f7 elementor-widget elementor-widget-text-editor\" data-id=\"5f9d88f7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nuestra intenci\u00f3n es la formaci\u00f3n de cuadros que nos permita atender las prioridades de desarrollo comunitario, por tal, te invitamos a participar. \u00a1Conoce c\u00f3mo hacerlo!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c821ed8 elementor-widget elementor-widget-accordion\" data-id=\"c821ed8\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2091\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-2091\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Formulario de registro como voluntario<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2091\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2091\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f495-o1\" lang=\"es-ES\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/81#wpcf7-f495-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"495\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f495-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> Tu nombre completo<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Tu correo electr\u00f3nico<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Tel\u00e9fono de contacto<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Telfono\"><input type=\"tel\" name=\"Telfono\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Ciudad y pa\u00eds donde vives<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ciudadypasdondevives\"><input type=\"text\" name=\"ciudadypasdondevives\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><br \/>\n <\/label><\/p>\n<p><label> Describe cu\u00e1l ser\u00eda tu principal aportaci\u00f3n en el proyecto de \u00abAcciones en comunidad\u00bb del Instituto V\u00eda Excelencia<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<p>Le agradecemos mucho su tiempo. Pronto le contactaremos.<\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Formulario de registro como voluntario\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<div role=\\\"form\\\" class=\\\"wpcf7\\\" id=\\\"wpcf7-f495-o2\\\" lang=\\\"es-ES\\\" dir=\\\"ltr\\\">\\n<div class=\\\"screen-reader-response\\\"><p role=\\\"status\\\" aria-live=\\\"polite\\\" aria-atomic=\\\"true\\\"><\\\/p> <ul><\\\/ul><\\\/div>\\n<form action=\\\"\\\/index.php\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/81#wpcf7-f495-o2\\\" method=\\\"post\\\" class=\\\"wpcf7-form init\\\" novalidate=\\\"novalidate\\\" data-status=\\\"init\\\">\\n<div style=\\\"display: none;\\\">\\n<input type=\\\"hidden\\\" name=\\\"_wpcf7\\\" value=\\\"495\\\" \\\/>\\n<input type=\\\"hidden\\\" name=\\\"_wpcf7_version\\\" value=\\\"5.6.3\\\" \\\/>\\n<input type=\\\"hidden\\\" name=\\\"_wpcf7_locale\\\" value=\\\"es_ES\\\" \\\/>\\n<input type=\\\"hidden\\\" name=\\\"_wpcf7_unit_tag\\\" value=\\\"wpcf7-f495-o2\\\" \\\/>\\n<input type=\\\"hidden\\\" name=\\\"_wpcf7_container_post\\\" value=\\\"0\\\" \\\/>\\n<input type=\\\"hidden\\\" name=\\\"_wpcf7_posted_data_hash\\\" value=\\\"\\\" \\\/>\\n<input type=\\\"hidden\\\" name=\\\"_wpcf7_recaptcha_response\\\" value=\\\"\\\" \\\/>\\n<\\\/div>\\n<p><label> Tu nombre completo<br \\\/>\\n    <span class=\\\"wpcf7-form-control-wrap\\\" data-name=\\\"your-name\\\"><input type=\\\"text\\\" name=\\\"your-name\\\" value=\\\"\\\" size=\\\"40\\\" class=\\\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\\\" aria-required=\\\"true\\\" aria-invalid=\\\"false\\\" \\\/><\\\/span> <\\\/label><\\\/p>\\n<p><label> Tu correo electr\\u00f3nico<br \\\/>\\n    <span class=\\\"wpcf7-form-control-wrap\\\" data-name=\\\"your-email\\\"><input type=\\\"email\\\" name=\\\"your-email\\\" value=\\\"\\\" size=\\\"40\\\" class=\\\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\\\" aria-required=\\\"true\\\" aria-invalid=\\\"false\\\" \\\/><\\\/span> <\\\/label><\\\/p>\\n<p><label> Tel\\u00e9fono de contacto<br \\\/>\\n<span class=\\\"wpcf7-form-control-wrap\\\" data-name=\\\"Telfono\\\"><input type=\\\"tel\\\" name=\\\"Telfono\\\" value=\\\"\\\" size=\\\"40\\\" class=\\\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\\\" aria-required=\\\"true\\\" aria-invalid=\\\"false\\\" \\\/><\\\/span> <\\\/label><\\\/p>\\n<p><label> Ciudad y pa\\u00eds donde vives<br \\\/>\\n<span class=\\\"wpcf7-form-control-wrap\\\" data-name=\\\"ciudadypasdondevives\\\"><input type=\\\"text\\\" name=\\\"ciudadypasdondevives\\\" value=\\\"\\\" size=\\\"40\\\" class=\\\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\\\" aria-required=\\\"true\\\" aria-invalid=\\\"false\\\" \\\/><\\\/span><br \\\/>\\n <\\\/label><\\\/p>\\n<p><label> Describe cu\\u00e1l ser\\u00eda tu principal aportaci\\u00f3n en el proyecto de \\u00abAcciones en comunidad\\u00bb del Instituto V\\u00eda Excelencia<br \\\/>\\n    <span class=\\\"wpcf7-form-control-wrap\\\" data-name=\\\"your-message\\\"><textarea name=\\\"your-message\\\" cols=\\\"40\\\" rows=\\\"10\\\" class=\\\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\\\" aria-required=\\\"true\\\" aria-invalid=\\\"false\\\"><\\\/textarea><\\\/span> <\\\/label><\\\/p>\\n<p><input type=\\\"submit\\\" value=\\\"Enviar\\\" class=\\\"wpcf7-form-control has-spinner wpcf7-submit\\\" \\\/><\\\/p>\\n<p>Le agradecemos mucho su tiempo. Pronto le contactaremos.<\\\/p>\\n<div class=\\\"wpcf7-response-output\\\" aria-hidden=\\\"true\\\"><\\\/div><\\\/form><\\\/div>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-902f12e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"902f12e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b34bbac\" data-id=\"b34bbac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46558800 elementor-widget elementor-widget-heading\" data-id=\"46558800\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Iniciativas<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2238e3c1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2238e3c1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6949dcf0\" data-id=\"6949dcf0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78b97830 elementor-widget elementor-widget-text-editor\" data-id=\"78b97830\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Son las propuestas de mejora y cambio social realizadas por los estudiantes, resultado de las actividades de aprendizaje de los diferentes espacios formativos del Instituto V\u00eda Excelencia.<\/p><p>Nuestros programas de formaci\u00f3n se encuentran dise\u00f1ados a partir de criterios de pertinencia social y factibilidad, por lo que nuestros estudiantes podr\u00e1n aplicar lo que aprenden en la integraci\u00f3n de propuestas de desarrollo comunitario que impacten de manera significativa.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d585982\" data-id=\"d585982\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1389287e elementor-widget elementor-widget-image\" data-id=\"1389287e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"591\" height=\"591\" src=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/05\/iconos-VE-Negro-11.png\" class=\"elementor-animation-grow attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/05\/iconos-VE-Negro-11.png 591w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/05\/iconos-VE-Negro-11-300x300.png 300w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/05\/iconos-VE-Negro-11-150x150.png 150w, https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/05\/iconos-VE-Negro-11-100x100.png 100w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51a1436e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51a1436e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a5ab761\" data-id=\"3a5ab761\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28370af8 elementor-widget elementor-widget-heading\" data-id=\"28370af8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Proyectos externos<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b45f49d elementor-widget elementor-widget-text-editor\" data-id=\"b45f49d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Se refiere a la colaboraci\u00f3n interinstitucional entre el Instituto V\u00eda Excelencia y otras organizaciones, personas o grupos de personas que realicen emprendimientos sociales.<\/p><p>\u00a0<\/p><p>Si deseas integrarnos a tus actividades o proyectos, cont\u00e1ctanos por favor:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3c4068\" data-id=\"d3c4068\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b27f23 elementor-widget elementor-widget-accordion\" data-id=\"3b27f23\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6201\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-6201\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Formulario de registro proyecto externo<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6201\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6201\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f549-o3\" lang=\"es-ES\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/81#wpcf7-f549-o3\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"549\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f549-o3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> Nombre de la instituci\u00f3n, agrupaci\u00f3n o persona:<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Descripci\u00f3n de la actividad o proyecto:<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><label> Apoyo que requieren del Instituto V\u00eda Excelencia:<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Requerimiento\"><textarea name=\"Requerimiento\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p>Datos de contacto:<br \/>\n<label> Correo electr\u00f3nico<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Tel\u00e9fono de contacto<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Telfono\"><input type=\"tel\" name=\"Telfono\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<p>Te agradecemos mucho su tiempo. Pronto te contactaremos.<\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>VinculACI\u00d3N cOMUNITARIA Principio de crecimiento de comunidades de aprendizaje En el Instituto V\u00eda Excelencia nos basamos en el principio del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":359,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vinculaci\u00f3n comunitaria - Instituto V\u00eda Excelencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vinculaci\u00f3n comunitaria - Instituto V\u00eda Excelencia\" \/>\n<meta property=\"og:description\" content=\"VinculACI\u00d3N cOMUNITARIA Principio de crecimiento de comunidades de aprendizaje En el Instituto V\u00eda Excelencia nos basamos en el principio del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto V\u00eda Excelencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutoviaexcelencia\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-26T14:28:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/06\/Banner_Vinculacion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"764\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/\",\"url\":\"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/\",\"name\":\"Vinculaci\u00f3n comunitaria - Instituto V\u00eda Excelencia\",\"isPartOf\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/#website\"},\"datePublished\":\"2021-03-31T05:36:52+00:00\",\"dateModified\":\"2021-07-26T14:28:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/viaexcelencia.com.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vinculaci\u00f3n comunitaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/#website\",\"url\":\"https:\/\/viaexcelencia.com.mx\/\",\"name\":\"Instituto V\u00eda Excelencia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/viaexcelencia.com.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/#organization\",\"name\":\"Instituto V\u00eda Excelencia\",\"url\":\"https:\/\/viaexcelencia.com.mx\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/institutoviaexcelencia\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/viaexcelencia.com.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Logotipo-VE-final-07.png\",\"contentUrl\":\"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Logotipo-VE-final-07.png\",\"width\":2629,\"height\":1021,\"caption\":\"Instituto V\u00eda Excelencia\"},\"image\":{\"@id\":\"https:\/\/viaexcelencia.com.mx\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vinculaci\u00f3n comunitaria - Instituto V\u00eda Excelencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/","og_locale":"es_ES","og_type":"article","og_title":"Vinculaci\u00f3n comunitaria - Instituto V\u00eda Excelencia","og_description":"VinculACI\u00d3N cOMUNITARIA Principio de crecimiento de comunidades de aprendizaje En el Instituto V\u00eda Excelencia nos basamos en el principio del [&hellip;]","og_url":"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/","og_site_name":"Instituto V\u00eda Excelencia","article_publisher":"https:\/\/www.facebook.com\/institutoviaexcelencia","article_modified_time":"2021-07-26T14:28:00+00:00","og_image":[{"width":764,"height":426,"url":"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/06\/Banner_Vinculacion.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/","url":"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/","name":"Vinculaci\u00f3n comunitaria - Instituto V\u00eda Excelencia","isPartOf":{"@id":"https:\/\/viaexcelencia.com.mx\/#website"},"datePublished":"2021-03-31T05:36:52+00:00","dateModified":"2021-07-26T14:28:00+00:00","breadcrumb":{"@id":"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/viaexcelencia.com.mx\/index.php\/vinculacion-comunitaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/viaexcelencia.com.mx\/"},{"@type":"ListItem","position":2,"name":"Vinculaci\u00f3n comunitaria"}]},{"@type":"WebSite","@id":"https:\/\/viaexcelencia.com.mx\/#website","url":"https:\/\/viaexcelencia.com.mx\/","name":"Instituto V\u00eda Excelencia","description":"","publisher":{"@id":"https:\/\/viaexcelencia.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viaexcelencia.com.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/viaexcelencia.com.mx\/#organization","name":"Instituto V\u00eda Excelencia","url":"https:\/\/viaexcelencia.com.mx\/","sameAs":["https:\/\/www.facebook.com\/institutoviaexcelencia"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/viaexcelencia.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Logotipo-VE-final-07.png","contentUrl":"https:\/\/viaexcelencia.com.mx\/wp-content\/uploads\/2021\/07\/Logotipo-VE-final-07.png","width":2629,"height":1021,"caption":"Instituto V\u00eda Excelencia"},"image":{"@id":"https:\/\/viaexcelencia.com.mx\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/81"}],"collection":[{"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=81"}],"version-history":[{"count":41,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/81\/revisions"}],"predecessor-version":[{"id":854,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/81\/revisions\/854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/media\/359"}],"wp:attachment":[{"href":"https:\/\/viaexcelencia.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}